{"id":3242,"date":"2023-05-22T17:34:59","date_gmt":"2023-05-22T15:34:59","guid":{"rendered":"http:\/\/www.amisdeportroyal.org\/societe\/?p=3242"},"modified":"2023-05-22T17:35:12","modified_gmt":"2023-05-22T15:35:12","slug":"un-poison-que-medee-apporta-dans-athenes-port-royal-et-le-theatre-3-juin-2023-port-royal-des-champs","status":"publish","type":"post","link":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/2023\/05\/22\/un-poison-que-medee-apporta-dans-athenes-port-royal-et-le-theatre-3-juin-2023-port-royal-des-champs\/","title":{"rendered":"\u00ab\u00a0Un poison que M\u00e9d\u00e9e apporta dans Ath\u00e8nes\u00a0\u00bb. Port-Royal et le th\u00e9\u00e2tre, 3 juin 2023, Port-Royal des Champs"},"content":{"rendered":"<p>La Soci\u00e9t\u00e9 des Amis de\u00a0<span class=\"il\">Port<\/span>&#8211;<span class=\"il\">Royal<\/span>, le Mus\u00e9e national de\u00a0<span class=\"il\">Port<\/span>&#8211;<span class=\"il\">Royal<\/span>\u00a0des Champs, le Centre International Jean Racine et le Centre de Recherche \u00c9diter-Interpr\u00e9ter de l&rsquo;Universit\u00e9 de Rouen, sont heureux de vous inviter \u00e0 une journ\u00e9e \u00e0 la fois studieuse et conviviale:<\/p>\n<p><b><i>\u00ab\u00a0Un poison que M\u00e9d\u00e9e apporta dans Ath\u00e8nes.\u00a0\u00bb\u00a0<span class=\"il\">Port<\/span>&#8211;<span class=\"il\">Royal<\/span>\u00a0et le\u00a0<span class=\"il\">th\u00e9\u00e2tre<\/span>.<\/i><\/b><\/p>\n<p>La journ\u00e9e se d\u00e9roulera \u00a0au\u00a0<b><a href=\"https:\/\/goo.gl\/maps\/oQb8axuwcsvgqMfb9\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/goo.gl\/maps\/oQb8axuwcsvgqMfb9&amp;source=gmail&amp;ust=1684851085921000&amp;usg=AOvVaw1WNHrvYGMXqaUvb6O1sKP6\">Mus\u00e9e national de\u00a0<span class=\"il\">Port<\/span>&#8211;<span class=\"il\">Royal<\/span>\u00a0des Champs<\/a><\/b>\u00a0(route des Granges 78114 Magny-les-Hameaux),\u00a0<b>le\u00a0samedi 3 juin de 9h15 \u00e0 17h<\/b><br \/>\nL&rsquo;affiche et le programme figurent ci-dessous et en pi\u00e8ce jointe.<\/p>\n<p><b><\/b>Page web de la journ\u00e9e:\u00a0<a href=\"https:\/\/annivracine.hypotheses.org\/44\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/annivracine.hypotheses.org\/44&amp;source=gmail&amp;ust=1684851085921000&amp;usg=AOvVaw2qwlIYzrS9_5Mep7XGxySn\">https:\/\/annivracine.<wbr \/>hypotheses.org\/44<\/a><br \/>\nRenseignements pratiques:\u00a0\u00a0<a href=\"mailto:anniversaires_raciniens@googlegroups.com\" target=\"_blank\" rel=\"noopener\">anniversaires_<wbr \/>raciniens@googlegroups.com<\/a><\/p>\n<p>En esp\u00e9rant vous retrouver nombreuses\/nombreux pour cette escapade printani\u00e8re dans ce lieu enchanteur,<\/p>\n<div>\n<div><i>C\u2019est l\u00e0 qu\u2019on dit que nos a\u00efeux,<br \/>\nAu si\u00e8cle d\u2019innocence,<br \/>\nGo\u00fbtaient les d\u00e9lices des cieux.<\/i><\/div>\n<div><\/div>\n<div><\/div>\n<div><b>PROGRAMME<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>\n<p>&nbsp;<\/p>\n<ul>\n<li>09h15 Accueil<\/li>\n<li>09h40 Pr\u00e9sentation de la journ\u00e9e<\/li>\n<li>10h00 Philippe Luez, \u201cIllustrer Racine\u201d, (Mus\u00e9e national de <span class=\"il\">Port<\/span>&#8211;<span class=\"il\">Royal<\/span> des Champs)<\/li>\n<li>10h40 Yosuke Morimoto,\u00a0 \u201cNicole et Escobar (et Cie) : une relecture du Trait\u00e9 de la Com\u00e9die\u201d, (Universit\u00e9 de Tokyo)<\/li>\n<li>11h20 Pause<\/li>\n<li>11h30 Servane L&rsquo;Hopital, \u201cJouer et prier. Analyse compar\u00e9e du Trait\u00e9 sur la com\u00e9die et du Trait\u00e9 sur la pri\u00e8re de Pierre Nicole\u201d (Lyc\u00e9e Malherbe de Caen)<\/li>\n<li>12h10 Tristan Alonge, \u201cLa tentation de Joad. Sur les traces d\u2019une th\u00e9ologie augustinienne dans Athalie\u201d (Universit\u00e9 de La R\u00e9union)<\/li>\n<li>12h50 D\u00e9jeuner sur place (sur inscription)<\/li>\n<li>14h30 Franc Schuerewegen, \u201cHistoire de nonnes, de signatures et de Bajazet\u201d (Universit\u00e9 d\u2019Anvers)<\/li>\n<li>15h10 Lauriane Maisonneuve, \u201cL\u2019ego racinien ou l\u2019int\u00e9gration de la contrainte jans\u00e9niste\u201d (Universit\u00e9 de Lyon-II)<\/li>\n<li>15h50\u00a0 Pause<\/li>\n<li>16h10\u00a0\u201cDroit \u00e0 la fiction et moralit\u00e9 du <span class=\"il\">th\u00e9\u00e2tre<\/span>, hier et aujourd\u2019hui\u201d, entretien avec L\u00e9na Paugam (compagnie Alexandre) anim\u00e9 par Tony Gheeraert<\/li>\n<li>17h00 Cl\u00f4ture de la journ\u00e9e<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Soci\u00e9t\u00e9 des Amis de\u00a0Port&#8211;Royal, le Mus\u00e9e national de\u00a0Port&#8211;Royal\u00a0des Champs, le Centre International Jean Racine et le Centre de Recherche \u00c9diter-Interpr\u00e9ter de l&rsquo;Universit\u00e9 de Rouen, sont heureux de vous inviter \u00e0 une journ\u00e9e \u00e0 la fois studieuse et conviviale: \u00ab\u00a0Un &hellip; <a href=\"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/2023\/05\/22\/un-poison-que-medee-apporta-dans-athenes-port-royal-et-le-theatre-3-juin-2023-port-royal-des-champs\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/posts\/3242"}],"collection":[{"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/comments?post=3242"}],"version-history":[{"count":2,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/posts\/3242\/revisions"}],"predecessor-version":[{"id":3246,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/posts\/3242\/revisions\/3246"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/media\/3244"}],"wp:attachment":[{"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/media?parent=3242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/categories?post=3242"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.amisdeportroyal.org\/societe\/index.php\/wp-json\/wp\/v2\/tags?post=3242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}